{"id":506,"date":"2019-03-18T13:54:24","date_gmt":"2019-03-18T11:54:24","guid":{"rendered":"http:\/\/www.bee-happy.net\/miel\/?p=506"},"modified":"2026-04-03T18:13:34","modified_gmt":"2026-04-03T16:13:34","slug":"a-propos-de-sandrine","status":"publish","type":"post","link":"https:\/\/www.bee-happy.net\/miel\/a-propos-de-sandrine\/","title":{"rendered":"A propos de Sandrine"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-x-large-font-size\" id=\"passion\">Passion <\/h2>\n\n\n\n<p class=\"has-drop-cap has-luminous-vivid-amber-background-color has-background has-medium-font-size wp-block-paragraph\" style=\"border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px\">Ce m\u00e9tier est tout d&rsquo;abord une passion, un partage et une entraide. J&rsquo;ai d\u00e9couvert les abeilles en 2004 cinq apr\u00e8s avoir d\u00e9pos\u00e9 mes valises dans la Haute Lande de Gascogne en pays d&rsquo;Albret. Double coup de foudre ! D&rsquo;abord j&rsquo;ai appris \u00e0 me faire adopter. A vaincre mes peurs infond\u00e9es. A me d\u00e9barrasser de mes \u00e0 priori stupides. Puis au fil du temps je me suis transform\u00e9e \u00e0 leur contact. Mes sens se sont r\u00e9v\u00e9l\u00e9s, en particulier mon sens olfactif. Je suis entr\u00e9e en communion avec elles. Mes intuitions m&rsquo;ont beaucoup aid\u00e9 et guid\u00e9.<\/p>\n\n\n\n<p class=\"has-drop-cap has-lightsecondarytag-background-color has-background has-medium-font-size wp-block-paragraph\" style=\"border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px\">Maintenant, je suis devenu la gardienne des abeilles dans le respect de leurs rythmes, en observant leurs comportements. Je pratique de <strong>l&rsquo;\u00e9levage naturel.<\/strong> Je ne fais pas de traitement syst\u00e9matique et surtout pas de chimie de synth\u00e8se. Chaque ruche est unique. Chacune est observ\u00e9e et b\u00e9n\u00e9ficie d&rsquo;une attention particuli\u00e8re pour \u00e9valuer ses besoins. Gr\u00e2ce \u00e0 l&rsquo;observation et aux connaissances recueillies aupr\u00e8s <strong>d&rsquo;amis-cultrices <\/strong>et de <strong>papis-culteurs,<\/strong> j&rsquo;arrive \u00e0 anticiper les comportements des colonies. Mon objectif est d&rsquo;\u00eatre pr\u00e9sente uniquement quand il le faut.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-x-large-font-size\" id=\"partage\">Partage<\/h2>\n\n\n\n<p class=\"has-drop-cap has-background has-medium-font-size wp-block-paragraph\" style=\"border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;background-color:#ff646159\">J&rsquo;aime partager . Je f\u00e9d\u00e8re autour de moi des int\u00e9r\u00eats communs, je cr\u00e9e des liens, j&rsquo;invite les bonnes volont\u00e9s \u00e0 partager et ressentir les bonnes vibrations \u00e9mises autour des ruchers. Les consciences s&rsquo;\u00e9veillent, et \u00e7a donne envie d&rsquo;avancer, de rechercher comment vivre libre avec la nature pour alli\u00e9. J&rsquo;anime des rencontres entre les abeilles et les enfants, les parents et les passionn\u00e9s.<\/p>\n\n\n\n<p class=\"has-drop-cap has-background has-medium-font-size wp-block-paragraph\" style=\"border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-left-radius:10px;border-bottom-right-radius:10px;background-color:#003f5c59\">Avec mon ami <strong>Alexandre l&rsquo;Herboriste <\/strong>et de nombreux volontaires qui&nbsp; nous aident, nous cr\u00e9ons sur la commune de Labrit, dans un cadre naturel pr\u00e9serv\u00e9, un lieu \u00e9cologique et ouvert. Nous utilisons des mat\u00e9riaux de r\u00e9cup\u00e9ration pour une leur donner une autre vie et des mat\u00e9riaux \u00e9cologiques locaux. La ressource est l\u00e0, tout autour de nous ! Argile, sable, bois, paille, pierre sont nos principaux mat\u00e9riaux pour la construction de ma miellerie saine et durable.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Passion Ce m\u00e9tier est tout d&rsquo;abord une passion, un partage et une entraide. J&rsquo;ai d\u00e9couvert les abeilles en 2004 cinq apr\u00e8s avoir d\u00e9pos\u00e9 mes valises dans la Haute Lande de Gascogne en pays d&rsquo;Albret. Double coup de foudre ! D&rsquo;abord j&rsquo;ai appris \u00e0 me faire adopter. A vaincre mes peurs infond\u00e9es. A me d\u00e9barrasser de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":509,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[12],"tags":[56,69,57,61,59,60],"class_list":["post-506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gardienne","tag-apicultrice","tag-partage","tag-passion","tag-profil","tag-sandrine","tag-sandrine-lefevre"],"jetpack_featured_media_url":"https:\/\/www.bee-happy.net\/miel\/wp-content\/uploads\/2019\/03\/Sandrine5.jpg","_links":{"self":[{"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/posts\/506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/comments?post=506"}],"version-history":[{"count":10,"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/posts\/506\/revisions"}],"predecessor-version":[{"id":3013,"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/posts\/506\/revisions\/3013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/media\/509"}],"wp:attachment":[{"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/media?parent=506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/categories?post=506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bee-happy.net\/miel\/wp-json\/wp\/v2\/tags?post=506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}